{"id":7,"count":2,"description":"","link":"https:\/\/crypto-house.net\/category\/bitcoin-altcoins\/emerging-altcoins\/","name":"Emerging Altcoins","slug":"emerging-altcoins","taxonomy":"category","parent":2,"meta":[],"_links":{"self":[{"href":"https:\/\/crypto-house.net\/de\/wp-json\/wp\/v2\/categories\/7","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/crypto-house.net\/de\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/crypto-house.net\/de\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/crypto-house.net\/de\/wp-json\/wp\/v2\/categories\/2"}],"wp:post_type":[{"href":"https:\/\/crypto-house.net\/de\/wp-json\/wp\/v2\/posts?categories=7"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}